{"id":128647,"date":"2026-04-04T12:51:01","date_gmt":"2026-04-04T15:51:01","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=128647"},"modified":"2026-04-04T12:51:01","modified_gmt":"2026-04-04T15:51:01","slug":"pelo-menos-13-deputados-estaduais-ja-trocaram-de-partido-veja-nomes-e-cenarios","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2026\/04\/04\/pelo-menos-13-deputados-estaduais-ja-trocaram-de-partido-veja-nomes-e-cenarios\/","title":{"rendered":"Pelo menos 13 deputados estaduais j\u00e1 trocaram de partido; veja nomes e cen\u00e1rios"},"content":{"rendered":"<div id=\"inner-news-body\" class=\"max-w-full break-words text-body-1 leading-normal tracking-tight text-neutral-20 [&amp;&gt;span]:inline-block [&amp;_*]:mb-6 last:[&amp;_*]:mb-0 [&amp;_h2]:text-[32px] [&amp;_h2]:font-bold [&amp;_h3]:text-[24px] [&amp;_h3]:font-semibold [&amp;_iframe]:!min-w-[unset] [&amp;_iframe]:!max-w-[560px] [&amp;_img]:!h-auto [&amp;_img]:!min-w-[unset] [&amp;_img]:!max-w-full [&amp;_ol]:ml-8 [&amp;_ol]:list-decimal [&amp;_p]:leading-relaxed [&amp;_table]:max-w-full [&amp;_table]:border [&amp;_table]:border-neutral-40 [&amp;_td]:border [&amp;_td]:border-neutral-40 [&amp;_tr]:border [&amp;_tr]:border-neutral-40 [&amp;_ul]:ml-8 [&amp;_ul]:list-disc [&amp;_video]:my-4 [&amp;_video]:!h-auto [&amp;_video]:!w-full [&amp;_video]:!min-w-[unset] [&amp;_video]:!max-w-full\">\n<p style=\"text-align: justify;\">H\u00e1 um dia do fechamento da janela partid\u00e1ria, ao menos 13 dos 63 deputados estaduais j\u00e1 selaram filia\u00e7\u00e3o na nova legenda pela qual v\u00e3o disputar a reelei\u00e7\u00e3o este ano.<\/p>\n<p style=\"text-align: justify;\">PV e Avante foram os partidos que mais receberam parlamentares, com tr\u00eas novos ingressos cada um. No primeiro caso, a sigla Verde perdeu Ludmilla Fiscina, que foi para o PSD, mas deu boas-vindas a Ant\u00f4nio Henrique J\u00fanior e Eduardo Salles egressos do PP e Fab\u00edola Mansur, que deixou para tr\u00e1s uma hist\u00f3ria de 18 anos com o PSB.<\/p>\n<p style=\"text-align: justify;\">O Avante, por sua vez, saiu de um para quatro parlamentares, com a chegada de Felipe Duarte (ex-PP), Laerte do Vando (ex-Podemos) e Vitor Azevedo (ex-PL), juntando-se a Patrick, \u00fanico estadual eleito no partido em 2022.<\/p>\n<p style=\"text-align: justify;\">O PSD manteve a bancada de nove estaduais, porque as sa\u00eddas de Angelo Coronel Filho e Cafu Barreto foram compensadas com as filia\u00e7\u00f5es de Niltinho (ex-PP) e Ludmilla. Tamb\u00e9m com nove deputados, o PT foi um dos poucos partidos que n\u00e3o tiveram mudan\u00e7a entre os de mandato.<\/p>\n<p style=\"text-align: justify;\">O Uni\u00e3o Brasil, que j\u00e1 havia perdido Marcinho Oliveira para o PRD antes mesmo da janela, tamb\u00e9m viu Marcelinho Veiga partir para o PP &#8211; legenda com a qual est\u00e1 em federa\u00e7\u00e3o, o que minimiza a migra\u00e7\u00e3o. Saiu, ent\u00e3o, de uma bancada de 10 para oito. O PP tamb\u00e9m foi o destino de Emerson Penalva (ex-PDT), que se junta a Veiga, Nelson Leal (que n\u00e3o ser\u00e1 candidato \u00e0 reelei\u00e7\u00e3o) e Hassan, que acompanha o posicionamento pol\u00edtico do prefeito de Jequi\u00e9, Z\u00e9 Coc\u00e1 (PP), vice na chapa de ACM Neto (Uni\u00e3o Brasil) ao governo do Estado.<\/p>\n<p style=\"text-align: justify;\">PCdoB, PL, MDB e Solidariedade mantiveram a mesma configura\u00e7\u00e3o sem nenhuma migra\u00e7\u00e3o. O mesmo acontece com PSDB e Republicanos, com a ressalva de que o deputado Samuel J\u00fanior pode ainda trocar a legenda da Igreja Universal por outro que viabilize a elei\u00e7\u00e3o de sua nova dobradinha federal, Abra\u00e3o Reis &#8211; substituto de Alex Santana. Os poss\u00edveis destinos seriam PL ou Uni\u00e3o Brasil.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, o Republicanos recepcionou Angelo Coronel Filho e deve tamb\u00e9m ficar com Cafu Barreto.<\/p>\n<p style=\"text-align: justify;\">Mudan\u00e7as j\u00e1 consolidadas:<\/p>\n<p style=\"text-align: justify;\">* Angelo Coronel Filho \u2192 PSD \u2192 Republicanos<br \/>\n* Cafu Barreto \u2192 PSD \u2192 possivelmente Republicanos<br \/>\n* Ant\u00f4nio Henrique Jr. \u2192 PP \u2192 PV<br \/>\n* Eduardo Salles \u2192 PP \u2192 PV<br \/>\n* Fab\u00edola Mansur \u2192 PSB \u2192 PV<br \/>\n* Felipe Duarte \u2192 PP \u2192 Avante<br \/>\n* Laerte do Vando \u2192 Podemos \u2192 Avante<br \/>\n* Vitor Azevedo \u2192 PL \u2192 Avante<br \/>\n* Ludmilla Fiscina \u2192 PV \u2192 PSD<br \/>\n* Niltinho \u2192 PP \u2192 PSD<br \/>\n* Penalva \u2192 PDT \u2192 PP<br \/>\n* Marcelinho Veiga \u2192 Uni\u00e3o Brasil \u2192 PP<br \/>\n* *Samuel J\u00fanior \u2192 poss\u00edvel sa\u00edda do Republicanos para Uni\u00e3o Brasil ou PL<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 um dia do fechamento da janela partid\u00e1ria, ao menos 13 dos 63 deputados estaduais j\u00e1 selaram filia\u00e7\u00e3o na nova legenda pela qual v\u00e3o disputar a reelei\u00e7\u00e3o este ano. PV e Avante foram os partidos que mais receberam parlamentares, com tr\u00eas novos ingressos cada um. No primeiro caso, a sigla Verde perdeu Ludmilla Fiscina, que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":128648,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[112,105],"tags":[183,7621,5790,1464,3308],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/128647"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=128647"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/128647\/revisions"}],"predecessor-version":[{"id":128649,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/128647\/revisions\/128649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/128648"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=128647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=128647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=128647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}