{"id":128385,"date":"2026-03-21T20:03:10","date_gmt":"2026-03-21T23:03:10","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=128385"},"modified":"2026-03-21T20:03:10","modified_gmt":"2026-03-21T23:03:10","slug":"seminario-promovido-por-waldenor-e-ze-raimundo-reune-mais-de-2-mil-pessoas-de-48-municipios-em-vitoria-da-conquista","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2026\/03\/21\/seminario-promovido-por-waldenor-e-ze-raimundo-reune-mais-de-2-mil-pessoas-de-48-municipios-em-vitoria-da-conquista\/","title":{"rendered":"Semin\u00e1rio promovido por Waldenor e Z\u00e9 Raimundo re\u00fane mais de 2 mil pessoas de 48 munic\u00edpios em Vit\u00f3ria da Conquista"},"content":{"rendered":"<p style=\"text-align: justify;\">O semin\u00e1rio \u201cEmendas Participativas e Desenvolvimento Regional: definindo prioridades com o povo\u201d, realizado neste s\u00e1bado (21), em Vit\u00f3ria da Conquista, consolidou-se como um dos maiores eventos pol\u00edticos promovidos por parlamentares no interior da Bahia.<\/p>\n<p style=\"text-align: justify;\">O encontro realizado na quadra do CETI (antigo Col\u00e9gio Abdias Menezes) reuniu mais de 2 mil pessoas e contou com a participa\u00e7\u00e3o de mais de uma centena de prefeitos, vice-prefeitos e vereadores, representando 48 munic\u00edpios, evidenciando a for\u00e7a da mobiliza\u00e7\u00e3o em torno da proposta de constru\u00e7\u00e3o coletiva das pol\u00edticas p\u00fablicas.<\/p>\n<p style=\"text-align: justify;\">Promovido pelo deputado federal Waldenor Pereira e pelo deputado estadual Z\u00e9 Raimundo, o semin\u00e1rio apresentou uma alternativa ao modelo do chamado \u201cor\u00e7amento secreto\u201d, alvo de cr\u00edticas pela falta de transpar\u00eancia. Em contraponto, os parlamentares defendem e praticam de forma in\u00e9dita este modelo de emendas participativas, baseado na escuta direta da popula\u00e7\u00e3o para defini\u00e7\u00e3o das prioridades de investimento.<\/p>\n<p style=\"text-align: justify;\">Ao destacar a proposta, Waldenor refor\u00e7ou o car\u00e1ter democr\u00e1tico da iniciativa: \u201cEstamos convocando a sociedade em nossa regi\u00e3o para decidir, de forma democr\u00e1tica, o destino de nossas emendas, porque defendemos a transpar\u00eancia na aplica\u00e7\u00e3o dos recursos p\u00fablicos. \u00c9 por isso que realizamos este semin\u00e1rio. Estamos fazendo um grande esfor\u00e7o para que voc\u00eas decidam onde devemos aplicar esses recursos.\u201d<\/p>\n<p style=\"text-align: justify;\">J\u00e1 o deputado Z\u00e9 Raimundo enfatizou o v\u00ednculo entre participa\u00e7\u00e3o popular e fortalecimento da democracia, al\u00e9m de criticar a falta de transpar\u00eancia no uso de emendas parlamentares: \u201cEssa ideia participativa tem a ver com a democracia. Infelizmente, todos os dias vemos den\u00fancias envolvendo emendas parlamentares, recursos p\u00fablicos sem transpar\u00eancia, que a popula\u00e7\u00e3o n\u00e3o sabe para onde v\u00e3o. Isso enfraquece a democracia. Por isso, precisamos democratizar, ampliar a participa\u00e7\u00e3o e garantir que o povo ajude a decidir, de forma clara, onde os recursos devem ser aplicados.\u201d<\/p>\n<p style=\"text-align: justify;\">O secret\u00e1rio estadual de Rela\u00e7\u00f5es Institucionais, Adolpho Loyola, tamb\u00e9m destacou o papel dos parlamentares na condu\u00e7\u00e3o do modelo participativo: \u201cWaldenor e Z\u00e9 Raimundo merecem toda a nossa aten\u00e7\u00e3o, porque s\u00e3o deputados que honram a Bahia, no Congresso Nacional e na Assembleia Legislativa, trabalhando para democratizar o uso das suas emendas parlamentares com transpar\u00eancia, para que os recursos cheguem aos munic\u00edpios, na ponta. \u00c9 assim que se trabalha com democracia e com debate.\u201d<\/p>\n<figure id=\"attachment_128387\" aria-describedby=\"caption-attachment-128387\" style=\"width: 500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-128387 size-full\" src=\"https:\/\/www.blogdopaulonunes.com\/v5\/wp-content\/uploads\/2026\/03\/mandato-deputados-Waldenor-e-Ze-Raimundo.jpg\" alt=\"\" width=\"500\" height=\"333\" \/><figcaption id=\"caption-attachment-128387\" class=\"wp-caption-text\">Mandato dos deputados Waldenor Pereira e Z\u00e9 Raimundo Fontes<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Para 2026, os recursos destinados por meio das emendas dos dois mandatos somam R$ 58 milh\u00f5es, que ser\u00e3o aplicados a partir das demandas apontadas pela popula\u00e7\u00e3o e lideran\u00e7as regionais, distribu\u00eddos de forma tem\u00e1tica (educa\u00e7\u00e3o, sa\u00fade, agricultura familiar, cultura, infraestrutura etc).<\/p>\n<p style=\"text-align: justify;\">O evento contou com representantes dos governos federal e estadual, incluindo o secret\u00e1rio estadual de Rela\u00e7\u00f5es Institucionais, Adolpho Loyola, o diretor-presidente da Companhia de Desenvolvimento e A\u00e7\u00e3o Regional (CAR), Jeandro Ribeiro, o coordenador executivo do Codes Bahia, Jonas Paulo, o presidente do PT Bahia, T\u00e1ssio Brito, o l\u00edder do governo na Assembleia Legislativa da Bahia (Alba), Rosenberg Pinto, e o chefe da Assessoria Especial no Minist\u00e9rio do Desenvolvimento Agr\u00e1rio e Agricultura Familiar (MDA), Eric Moura, representando o ministro Paulo Teixeira.<\/p>\n<p style=\"text-align: justify;\">Entre as lideran\u00e7as municipais presentes, destacaram-se os prefeitos Fabr\u00edcio Abrantes (Brumado), Fernando Silva Santos (Dom Bas\u00edlio), Cloves Andrade (Planalto), Edinho do Maracuj\u00e1 (Mirante), S\u00e9rgio (Maetinga), Pedrinho (Encruzilhada), Dr. Humberto (Caatiba) Doe( Nova Cana\u00e3) e Braulina (Aracatu). Tamb\u00e9m participaram os vice-prefeitos Ronaldo (Carinhanha), Gon\u00e7alo (Malhada de Pedras),e Jo\u00e3o Bonfim (Po\u00e7\u00f5es).<\/p>\n<p style=\"text-align: justify;\">Ao reunir ampla representa\u00e7\u00e3o pol\u00edtica e social, o semin\u00e1rio reafirma o compromisso com a transpar\u00eancia, a participa\u00e7\u00e3o popular e o desenvolvimento regional, fortalecendo um modelo de gest\u00e3o que coloca a popula\u00e7\u00e3o no centro das decis\u00f5es sobre o uso dos recursos p\u00fablicos, conforme avaliaram Waldenor Pereira e Z\u00e9 Raimundo, comemorando o \u00eaxito do evento, que tamb\u00e9m deu uma grande demonstra\u00e7\u00e3o de for\u00e7a e mobiliza\u00e7\u00e3o dos dois mandatos.<\/p>\n<p style=\"text-align: justify;\">Fotos: comunica\u00e7\u00e3o WZ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O semin\u00e1rio \u201cEmendas Participativas e Desenvolvimento Regional: definindo prioridades com o povo\u201d, realizado neste s\u00e1bado (21), em Vit\u00f3ria da Conquista, consolidou-se como um dos maiores eventos pol\u00edticos promovidos por parlamentares no interior da Bahia. O encontro realizado na quadra do CETI (antigo Col\u00e9gio Abdias Menezes) reuniu mais de 2 mil pessoas e contou com a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":128386,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[81,105],"tags":[7883,7861,6920,721,166],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/128385"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=128385"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/128385\/revisions"}],"predecessor-version":[{"id":128388,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/128385\/revisions\/128388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/128386"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=128385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=128385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=128385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}