{"id":128020,"date":"2026-03-05T06:31:53","date_gmt":"2026-03-05T09:31:53","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=128020"},"modified":"2026-03-05T06:31:53","modified_gmt":"2026-03-05T09:31:53","slug":"em-mensagens-vorcaro-chama-ciro-nogueira-de-grande-amigo-e-autoriza-suposto-pagamento-ao-senador","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2026\/03\/05\/em-mensagens-vorcaro-chama-ciro-nogueira-de-grande-amigo-e-autoriza-suposto-pagamento-ao-senador\/","title":{"rendered":"Em mensagens, Vorcaro chama Ciro Nogueira de \u201cgrande amigo\u201d e autoriza suposto pagamento ao senador"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Mensagens obtidas pela PF no celular de Daniel Vorcaro mostram que o banqueiro mantinha di\u00e1logo com Ciro Nogueira e que chegou a comemorar uma emenda do senador que beneficiaria o Banco Master<\/strong><\/p>\n<p style=\"text-align: justify;\">ensagens encontradas pela Pol\u00edcia Federal (PF) no celular do banqueiro\u00a0<a href=\"https:\/\/revistaforum.com.br\/politica\/a-turma-vorcaro-foi-preso-por-obstrucao-e-ameacas-violentas-a-adversarios-incluindo-jornalistas\/\" target=\"_blank\" rel=\"noopener\">Daniel Vorcaro<\/a>\u00a0indicam<strong>\u00a0proximidade<\/strong>\u00a0entre o empres\u00e1rio e o senador\u00a0<a href=\"https:\/\/revistaforum.com.br\/politica\/ciro-nogueira-confirma-relacao-com-daniel-vorcaro-e-se-explica-sobre-emenda-master-veja-video\/\" target=\"_blank\" rel=\"noopener\">Ciro Nogueira (PP-PI)<\/a>, ex-ministro da Casa Civil de Jair Bolsonaro e uma das principais lideran\u00e7as do centr\u00e3o no Congresso. Nos di\u00e1logos, Vorcaro se refere ao parlamentar como\u00a0<strong>\u201cgrande amigo de vida\u201d<\/strong>, comemora uma emenda apresentada por ele que beneficiaria o Banco Master e chega a\u00a0<strong>autorizar um pagamento a uma pessoa identificada apenas como \u201cCiro\u201d<\/strong>.<\/p>\n<p style=\"text-align: justify;\">O material foi obtido durante a investiga\u00e7\u00e3o sobre o Banco Master e j\u00e1 foi encaminhado ao ministro do Supremo Tribunal Federal (STF) Andr\u00e9 Mendon\u00e7a, respons\u00e1vel por decretar a pris\u00e3o preventiva de Vorcaro, cumprida pela PF nesta quarta-feira (4).<\/p>\n<p style=\"text-align: justify;\">As mensagens mostram que Vorcaro mantinha conversas frequentes com o senador, que \u00e9 presidente nacional do PP. Segundo investigadores, os di\u00e1logos tratam de assuntos pol\u00edticos, amenidades e organiza\u00e7\u00e3o de encontros presenciais. Uma das mensagens, por\u00e9m, aponta suposto pagamento ordenado por Vorcaro a Ciro. At\u00e9 o momento, n\u00e3o h\u00e1 inqu\u00e9rito formal aberto contra o senador no \u00e2mbito da investiga\u00e7\u00e3o.<\/p>\n<h3 style=\"text-align: justify;\" data-start=\"1472\" data-end=\"1508\">Emenda que beneficiaria o Master<\/h3>\n<p style=\"text-align: justify;\" data-start=\"1510\" data-end=\"1781\">Em uma troca de mensagens com sua companheira, a blogueira Martha Graeff, Vorcaro apresenta o senador como algu\u00e9m muito pr\u00f3ximo. \u201cCiro nogueira. \u00c9 um senador. Muito amigo meu. Quero te apresentar. Um dos meus grandes amigos de vida\u201d, escreveu o banqueiro em maio de 2024.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1783\" data-end=\"2132\">Meses depois, ele voltou a citar o parlamentar ao comentar uma iniciativa legislativa apresentada por Nogueira. \u201cCiro soltou um projeto de lei agora que \u00e9 uma bomba at\u00f4mica mercado financeiro! Ajuda os bancos m\u00e9dios e diminui poder dos grandes! Esta todo mundo louco\u201d, escreveu Vorcaro. Martha respondeu: \u201cWow amor. Louca pra saber de tudo ao vivo\u201d.<\/p>\n<p style=\"text-align: justify;\" data-start=\"2134\" data-end=\"2437\">A conversa ocorreu em 13 de agosto de 2024, data em que o senador apresentou uma emenda \u00e0 Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) que trata da autonomia financeira do Banco Central. O texto sugeria elevar o limite de cobertura do Fundo Garantidor de Cr\u00e9dito (FGC) de R$ 250 mil para R$ 1 milh\u00e3o por CPF.<\/p>\n<p style=\"text-align: justify;\" data-start=\"2439\" data-end=\"2709\">O modelo de neg\u00f3cios do Banco Master estava fortemente baseado na emiss\u00e3o de Certificados de Dep\u00f3sito Banc\u00e1rio (CDBs) com garantia do FGC. Com a amplia\u00e7\u00e3o do teto de cobertura, os t\u00edtulos emitidos pela institui\u00e7\u00e3o passariam a contar com prote\u00e7\u00e3o maior para investidores.<\/p>\n<p style=\"text-align: justify;\" data-start=\"2711\" data-end=\"2968\">Por causa desse impacto potencial, a proposta ficou conhecida nos bastidores do mercado financeiro e do Congresso como \u201cemenda Master\u201d. A iniciativa acabou n\u00e3o avan\u00e7ando ap\u00f3s resist\u00eancia de entidades ligadas ao setor banc\u00e1rio e a PEC segue parada no Senado.<\/p>\n<h3 data-start=\"2970\" data-end=\"3019\">Autoriza\u00e7\u00e3o de pagamento<\/h3>\n<p style=\"text-align: justify;\" data-start=\"3021\" data-end=\"3298\">Al\u00e9m das mensagens sobre a emenda, a PF identificou ind\u00edcios de um poss\u00edvel pagamento associado ao nome \u201cCiro\u201d. Em maio de 2024, Fabiano Zettel, cunhado de Vorcaro e apontado como seu operador financeiro, enviou ao banqueiro uma lista com solicita\u00e7\u00f5es de repasses.<\/p>\n<p style=\"text-align: justify;\" data-start=\"3300\" data-end=\"3453\">\u201cPreciso que me ordene as prioridades. [\u2026] 2. Pagamento pra Ciro\u201d, escreveu Zettel. Na sequ\u00eancia, Vorcaro autorizou os pagamentos mencionados na lista.<\/p>\n<p style=\"text-align: justify;\" data-start=\"3455\" data-end=\"3637\">Os investigadores ainda n\u00e3o tiveram acesso aos dados banc\u00e1rios relacionados \u00e0 transa\u00e7\u00e3o e, por isso, n\u00e3o confirmaram se o destinat\u00e1rio era o senador ou outra pessoa com o mesmo nome.<\/p>\n<p style=\"text-align: justify;\" data-start=\"3639\" data-end=\"3934\">Outra conversa analisada pela investiga\u00e7\u00e3o envolve o deputado federal Fausto Pinato (PP-SP). Na mensagem, o parlamentar sugere um encontro virtual com o senador. \u201cOi, amigo, precisamos fazer a v\u00eddeo confer\u00eancia [sic] eu vc e Ciro\u201d, escreveu Pinato. Vorcaro respondeu: \u201cOpa. Vamos. S\u00f3 me chamar\u201d.<\/p>\n<p style=\"text-align: justify;\" data-start=\"3936\" data-end=\"4235\">As mensagens tamb\u00e9m mostram que o banqueiro demonstrava interesse em participar de eventos da fam\u00edlia do senador. Em di\u00e1logo com Martha Graeff, ele menciona o casamento de Duda Nogueira, filha de Ciro, realizado em agosto de 2024, e afirma que gostaria que a companheira o acompanhasse na cerim\u00f4nia.<\/p>\n<p style=\"text-align: justify;\" data-start=\"4237\" data-end=\"4496\">Procurado, Ciro Nogueira afirmou conhecer Vorcaro, mas negou proximidade e qualquer pagamento relacionado ao caso. \u201cInferir que se refere a mim, senador Ciro Nogueira, \u00e9 definitivamente uma mentira fabricada na tentativa de manchar minha biografia\u201d, declarou.<\/p>\n<p style=\"text-align: justify;\" data-start=\"4498\" data-end=\"4843\">Em outro posicionamento enviado por sua assessoria, o senador disse que troca mensagens com muitas pessoas. \u201cCiro Nogueira volta a destacar que est\u00e1 tranquilo quanto \u00e0s investiga\u00e7\u00f5es da Pol\u00edcia Federal nas den\u00fancias que envolvem o empres\u00e1rio, uma vez que n\u00e3o mant\u00e9m nem nunca manteve qualquer conduta inadequada relacionada ao caso em apura\u00e7\u00e3o.\u201d<\/p>\n<p style=\"text-align: justify;\" data-start=\"4845\" data-end=\"5079\" data-is-last-node=\"\" data-is-only-node=\"\">A defesa de Daniel Vorcaro n\u00e3o se manifestou. Investigadores continuam analisando os dados extra\u00eddos do celular do banqueiro para verificar se h\u00e1 ind\u00edcios de crimes envolvendo agentes pol\u00edticos no esc\u00e2ndalo que atingiu o Banco Master.<\/p>\n<h2 data-start=\"4845\" data-end=\"5079\">Direita e centr\u00e3o em peso no celular de Vorcaro<\/h2>\n<p style=\"text-align: justify;\">Os\u00a0\u00e2nimos est\u00e3o \u00e0 flor da pele\u00a0em Bras\u00edlia ferveu nesta quarta-feira (4) ap\u00f3s\u00a0<a href=\"https:\/\/revistaforum.com.br\/politica\/a-turma-vorcaro-foi-preso-por-obstrucao-e-ameacas-violentas-a-adversarios-incluindo-jornalistas\/\">a Pol\u00edcia Federal cumprir mandados de pris\u00e3o contra o ex-dono do Banco Master<\/a>, Daniel Vorcaro, e seu s\u00f3cio e cunhado, Fabiano Zettel. A ordem partiu do ministro do STF, Andr\u00e9 Mendon\u00e7a, motivada por uma descoberta estarrecedora: o grupo estaria planejando ataques f\u00edsicos e atos de viol\u00eancia extrema,\u00a0que poderiam incluir agress\u00f5es ou at\u00e9 assassinatos,\u00a0contra desafetos e jornalistas,\u00a0<a href=\"https:\/\/revistaforum.com.br\/politica\/vorcaro-em-mensagem-esse-lauro-jardim-quero-mandar-dar-um-pau-nele\/\">entre eles Lauro Jardim, do jornal O Globo<\/a>.<\/p>\n<p style=\"text-align: justify;\">Mas histeria tomou conta mesmo do ambiente com as primeiras revela\u00e7\u00f5es do que foi extra\u00eddo do iPhone 17\u00a0de Vorcaro, apreendido numa\u00a0opera\u00e7\u00e3o anterior. O aparelho, identificado por investigadores como o n\u00famero \u201ccomercial\u201d\u00a0do banqueiro, mostrou\u00a0uma agenda que funciona como um verdadeiro mapa do poder bolsonarista na C\u00e2mara dos Deputados. A F\u00f3rum confirmou com uma fonte ligada \u00e0 CPMI do INSS os dados que vinham ventilados desde as primeiras horas da manh\u00e3 por internautas. S\u00e3o, de fato,\u00a018 nomes de parlamentares e ex-parlamentares encontrados\u00a0no dispositivo, todos ligados \u00e0 direita\u00a0e \u00e0 extrema direita, e por consequ\u00eancia,\u00a0ao bolsonarismo. N\u00e3o h\u00e1 um \u00fanico registro de integrantes do PT, PCdoB, PSB ou de qualquer legenda da base governista.<\/p>\n<p style=\"text-align: justify;\">A an\u00e1lise partid\u00e1ria dos 18 nomes revela o DNA bolsonarista da agenda de Vorcaro: o PL lidera com 5 representantes, seguido pelo PP com 4, o PSD com 3, enquanto Republicanos e Novo aparecem com 2 cada, e as legendas Uni\u00e3o Brasil e PSDB fecham a rela\u00e7\u00e3o com 1 nome cada.<\/p>\n<p style=\"text-align: justify;\"><strong>A lista dos 18: O n\u00facleo duro do celular de Vorcaro<\/strong><\/p>\n<p>Abaixo, os nomes encontrados na agenda institucional do banqueiro preso, que incluem desde o atual presidente da C\u00e2mara at\u00e9 figuras centrais da atual oposi\u00e7\u00e3o:<\/p>\n<ul>\n<li>Aguinaldo Ribeiro (PP-PB)\u00a0\u2013 Deputado federal<\/li>\n<li>Altineu C\u00f4rtes (PL-RJ)\u00a0\u2013 Deputado federal<\/li>\n<li>Arthur Lira (PP-AL)\u00a0\u2013 Deputado federal\u00a0(ex-pres. da C\u00e2mara)<\/li>\n<li>Bilac Pinto (Uni\u00e3o Brasil-MG)\u00a0\u2013 Ex-deputado federal<\/li>\n<li><span style=\"color: #ff0000;\">Diego Coronel (PSD-BA)\u00a0\u2013 Deputado federal<\/span><\/li>\n<li>Doutor Luizinho (PP-RJ)\u00a0\u2013 Deputado federal<\/li>\n<li>F\u00e1bio Mitidieri (PSD-SE)\u00a0\u2013 Ex-deputado federal<\/li>\n<li>Fausto Pinato (PP-SP)\u00a0\u2013 Deputado federal<\/li>\n<li>Fl\u00e1via Arruda (PL-DF)\u00a0\u2013 Ex-deputada federal<\/li>\n<li>Hugo Motta (Republicanos-PB)\u00a0\u2013 Deputado federal\u00a0(atual pres. da C\u00e2mara)<\/li>\n<li><span style=\"color: #ff0000;\">Jo\u00e3o Carlos Bacelar (PL-BA)\u00a0\u2013 Deputado federal<\/span><\/li>\n<li>Lucas Gonzalez (Novo-MG)\u00a0\u2013 Ex-deputado federal<\/li>\n<li>Marcelo \u00c1lvaro Ant\u00f4nio (PL-MG)\u00a0\u2013 Deputado federal<\/li>\n<li><span style=\"color: #ff0000;\">M\u00e1rcio Marinho (Republicanos-BA)\u00a0\u2013 Deputado federal<\/span><\/li>\n<li>Nikolas Ferreira (PL-MG)\u00a0\u2013 Deputado federal<\/li>\n<li>Paulo Abi-Ackel (PSDB-MG)\u00a0\u2013 Deputado federal<\/li>\n<li>Rodrigo Maia (PSD-RJ)\u00a0\u2013 Ex-deputado federal\u00a0(ex-pres. da C\u00e2mara)<\/li>\n<li>Vinicius Poit (Novo-SP)\u00a0\u2013 Ex-deputado federal<\/li>\n<\/ul>\n<h2>O moralista\u00a0Nikolas, do jatinho de\u00a0campanha, est\u00e1 l\u00e1<\/h2>\n<p style=\"text-align: justify;\">O nome de Nikolas Ferreira (PL-MG)\u00a0salta aos olhos na lista do celular de Vorcaro n\u00e3o apenas pela sua postura de paladino da moralidade nas redes, mas pela reincid\u00eancia. A presen\u00e7a do deputado mineiro na agenda ocorre apenas 24 horas ap\u00f3s vir a p\u00fablico que\u00a0<a href=\"https:\/\/revistaforum.com.br\/politica\/video-nikolas-ri-e-age-de-forma-infantil-a-descoberta-de-que-ele-usava-aviao-de-vorcaro\/\">Nikolas utilizou o jatinho privado do banqueiro\u00a0durante a campanha de 2022<\/a>.<\/p>\n<p style=\"text-align: justify;\">Enquanto discursava para as bases bolsonaristas, o parlamentar cruzava o c\u00e9u em uma aeronave cedida pelo bilion\u00e1rio agora preso por planejar atentados\u00a0a jornalistas. O uso do jatinho em agendas vinculadas \u00e0 reelei\u00e7\u00e3o de Jair Bolsonaro (PL) j\u00e1 havia inserido o banqueiro no radar pol\u00edtico-eleitoral, mas a lista do iPhone 17 mostra que a conex\u00e3o era direta e catalogada.<\/p>\n<h2>A tentativa frustrada de \u201cterceirizar\u201d\u00a0o esc\u00e2ndalo<\/h2>\n<p style=\"text-align: justify;\">Desde que as irregularidades envolvendo o Banco Master e Vorcaro come\u00e7aram a emergir, parlamentares bolsonaristas tentaram criar uma cortina de fuma\u00e7a, buscando empurrar o esc\u00e2ndalo para o colo do governo Lula\u00a0(PT). No entanto, os fatos s\u00e3o teimosos.<\/p>\n<p style=\"text-align: justify;\">As investiga\u00e7\u00f5es mostram que o tr\u00e2nsito de Vorcaro era exclusivamente\u00a0dentro do campo da direita\u00a0e extrema-direita. O fato de o aparelho \u201ccomercial\u201d\u00a0concentrar figuras como o atual presidente da C\u00e2mara, Hugo Motta (Republicanos-PB), e seu antecessor, Arthur Lira (PP-AL), refor\u00e7a que o banqueiro mantinha uma rede de interlocu\u00e7\u00e3o institucional de alt\u00edssimo n\u00edvel, mas estritamente restrita a um espectro pol\u00edtico.<\/p>\n<p style=\"text-align: justify;\">A aus\u00eancia de qualquer nome de esquerda ou centro-esquerda na lista desmonta a narrativa de \u201cesc\u00e2ndalo generalizado\u201d\u00a0e isola o caso como um imbr\u00f3glio que nasce e se cria dentro dos gabinetes mais pr\u00f3ximos ao ex-presidente Jair Bolsonaro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mensagens obtidas pela PF no celular de Daniel Vorcaro mostram que o banqueiro mantinha di\u00e1logo com Ciro Nogueira e que chegou a comemorar uma emenda do senador que beneficiaria o Banco Master ensagens encontradas pela Pol\u00edcia Federal (PF) no celular do banqueiro\u00a0Daniel Vorcaro\u00a0indicam\u00a0proximidade\u00a0entre o empres\u00e1rio e o senador\u00a0Ciro Nogueira (PP-PI), ex-ministro da Casa Civil de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":128021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4381,105],"tags":[1163,5423,3847,368,1933,7743],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/128020"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=128020"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/128020\/revisions"}],"predecessor-version":[{"id":128022,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/128020\/revisions\/128022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/128021"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=128020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=128020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=128020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}