{"id":127086,"date":"2025-12-26T19:20:08","date_gmt":"2025-12-26T22:20:08","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=127086"},"modified":"2025-12-26T19:20:08","modified_gmt":"2025-12-26T22:20:08","slug":"oea-frustra-bolsonaro-e-reconhece-tentativa-de-golpe-no-brasil","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2025\/12\/26\/oea-frustra-bolsonaro-e-reconhece-tentativa-de-golpe-no-brasil\/","title":{"rendered":"OEA frustra Bolsonaro e reconhece tentativa de golpe no Brasil"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Relat\u00f3rio da CIDH frustra expectativas do bolsonarismo ao afirmar que houve ataque \u00e0 democracia e ao apontar institui\u00e7\u00f5es s\u00f3lidas e elei\u00e7\u00f5es livres no pa\u00eds.<\/strong><\/p>\n<p style=\"text-align: justify;\">O relat\u00f3rio sobre liberdade de express\u00e3o divulgado nesta sexta-feira pela Comiss\u00e3o Interamericana de Direitos Humanos (CIDH) trouxe conclus\u00f5es que contrariam a narrativa constru\u00edda por aliados do ex-presidente Jair Bolsonaro ap\u00f3s encontros com representantes do \u00f3rg\u00e3o. O documento reconhece que o Brasil enfrentou uma tentativa de golpe de Estado ap\u00f3s as elei\u00e7\u00f5es de 2022 e atribui papel central ao Supremo Tribunal Federal (STF) na apura\u00e7\u00e3o dos fatos e na defesa da ordem democr\u00e1tica.<\/p>\n<p style=\"text-align: justify;\">Segundo o texto, houve a\u00e7\u00f5es deliberadas para desacreditar o resultado das elei\u00e7\u00f5es presidenciais. \u201cA Relatoria entende que o Brasil passou por tentativas deliberadas de deslegitimar os resultados eleitorais internacionalmente reconhecidos do per\u00edodo eleitoral de 2022, al\u00e9m do planejamento e da tentativa de execu\u00e7\u00e3o de um golpe de Estado\u201d, afirma o relat\u00f3rio. Em outro trecho, a comiss\u00e3o ressalta que \u201ca defesa da democracia no Brasil tamb\u00e9m \u00e9 um componente fundamental da defesa do direito \u00e0 liberdade de express\u00e3o no pa\u00eds\u201d.<\/p>\n<p style=\"text-align: justify;\">Ao abordar a atua\u00e7\u00e3o do Supremo Tribunal Federal, a CIDH reconhece a import\u00e2ncia das medidas adotadas, mas faz uma ressalva quanto aos riscos institucionais. \u201cO Supremo Tribunal Federal desempenhou um papel fundamental ao iniciar procedimentos para investigar e resolver essa situa\u00e7\u00e3o\u201d, diz o texto. Em seguida, alerta: \u201cNo entanto, tamb\u00e9m h\u00e1 preocupa\u00e7\u00f5es de que essas medidas constituam uma concentra\u00e7\u00e3o de poder\u201d. A comiss\u00e3o pondera ainda que \u201ch\u00e1 o risco de transformar uma solu\u00e7\u00e3o tempor\u00e1ria, destinada a ser excepcional, em um problema duradouro, ao criar precedentes que podem ser usados em benef\u00edcio de regimes potencialmente autorit\u00e1rios no futuro\u201d.<\/p>\n<p style=\"text-align: justify;\">Apesar dessa observa\u00e7\u00e3o, o relat\u00f3rio \u00e9 amplamente cr\u00edtico \u00e0s reivindica\u00e7\u00f5es do bolsonarismo. Durante a visita ao Brasil, o relator Pedro Vaca Villarreal chegou a se reunir com Bolsonaro, que demonstrou otimismo ap\u00f3s o encontro. Ainda assim, o documento final n\u00e3o endossou as cr\u00edticas ao Judici\u00e1rio feitas pelo ex-presidente e seus apoiadores.<\/p>\n<p style=\"text-align: justify;\">A CIDH tamb\u00e9m contextualiza o cen\u00e1rio pol\u00edtico brasileiro a partir de um olhar hist\u00f3rico, destacando marcas deixadas pela ditadura militar. O texto aponta que o pa\u00eds carrega \u201cmarcas de autoritarismo e desigualdade estrutural que informam a divis\u00e3o social de poderes e direitos\u201d. Para a comiss\u00e3o, \u201ca falta de uma resolu\u00e7\u00e3o completa desse passado ditatorial, sem iniciativas suficientes de mem\u00f3ria, verdade e justi\u00e7a, levou \u00e0 sobreviv\u00eancia acr\u00edtica de sintomas, discursos, formas de exerc\u00edcio do poder e atitudes autorit\u00e1rias\u201d.<\/p>\n<p style=\"text-align: justify;\">Outro ponto abordado \u00e9 o uso seletivo do discurso da liberdade de express\u00e3o. Segundo o relat\u00f3rio, \u201calguns dos atores que mais energicamente se referem ao direito \u00e0 liberdade de express\u00e3o desconsideram o fato de que o Estado, em todos seus momentos pol\u00edticos e por meio de diversos \u00f3rg\u00e3os federais e estaduais, historicamente tem usado e continua usando a\u00e7\u00f5es repressivas, incluindo o poder policial, contra os grupos mais vulner\u00e1veis da popula\u00e7\u00e3o\u201d.<\/p>\n<p style=\"text-align: justify;\">A comiss\u00e3o tamb\u00e9m avaliou a integridade do processo eleitoral brasileiro e o funcionamento das institui\u00e7\u00f5es. Em sentido oposto \u00e0s acusa\u00e7\u00f5es difundidas ap\u00f3s o pleito de 2022, o relat\u00f3rio conclui que \u201co Brasil possui institui\u00e7\u00f5es democr\u00e1ticas fortes e eficazes\u201d e que \u201co Estado realiza elei\u00e7\u00f5es livres e justas, e \u00e9 caracterizado pela separa\u00e7\u00e3o de poderes e pelo Estado de Direito\u201d.<\/p>\n<p style=\"text-align: justify;\">Mesmo com o alerta sobre poss\u00edveis excessos do Judici\u00e1rio, a CIDH afirma ter identificado \u201cuma clara separa\u00e7\u00e3o funcional dos poderes, autonomia judicial e um sistema de freios e contrapesos em pleno funcionamento\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Relat\u00f3rio da CIDH frustra expectativas do bolsonarismo ao afirmar que houve ataque \u00e0 democracia e ao apontar institui\u00e7\u00f5es s\u00f3lidas e elei\u00e7\u00f5es livres no pa\u00eds. O relat\u00f3rio sobre liberdade de express\u00e3o divulgado nesta sexta-feira pela Comiss\u00e3o Interamericana de Direitos Humanos (CIDH) trouxe conclus\u00f5es que contrariam a narrativa constru\u00edda por aliados do ex-presidente Jair Bolsonaro ap\u00f3s encontros [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":127087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4888,105],"tags":[327,7393],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/127086"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=127086"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/127086\/revisions"}],"predecessor-version":[{"id":127088,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/127086\/revisions\/127088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/127087"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=127086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=127086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=127086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}