{"id":126562,"date":"2025-11-25T00:28:55","date_gmt":"2025-11-25T03:28:55","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=126562"},"modified":"2025-11-25T00:28:55","modified_gmt":"2025-11-25T03:28:55","slug":"nova-lei-amplia-acesso-a-fisioterapia-no-sus-apos-mastectomia","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2025\/11\/25\/nova-lei-amplia-acesso-a-fisioterapia-no-sus-apos-mastectomia\/","title":{"rendered":"Nova lei amplia acesso \u00e0 fisioterapia no SUS ap\u00f3s mastectomia"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Tratamento \u00e9 condicionado \u00e0 realiza\u00e7\u00e3o de procedimento cir\u00fargico de remo\u00e7\u00e3o parcial ou total da mama.<\/strong><\/p>\n<p style=\"text-align: justify;\">O presidente da Rep\u00fablica em exerc\u00edcio, Geraldo Alckmin, sancionou a Lei\u00a0<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_Ato2023-2026\/2025\/Lei\/L15267.htm\" target=\"_blank\" rel=\"noopener\">15.267\/2025<\/a>, que assegura a assist\u00eancia fisioterap\u00eautica para pacientes que passaram por mastectomia. A medida determina que o Sistema \u00danico de Sa\u00fade (SUS) ofere\u00e7a fisioterapia \u00e0s pessoas submetidas ao procedimento cir\u00fargico de remo\u00e7\u00e3o parcial ou total da mama, utilizado no tratamento do c\u00e2ncer.<\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s publica\u00e7\u00e3o no Di\u00e1rio Oficial da Uni\u00e3o (DOU) desta segunda-feira (24), a lei deve ter in\u00edcio em 180 dias. A Lei\u00a0<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l9797.htm\" target=\"_blank\" rel=\"noopener\">9.797\/1999<\/a>\u00a0j\u00e1 garante \u00e0s mulheres submetidas \u00e0 mastectomia o direito \u00e0 cirurgia pl\u00e1stica reconstrutiva. A nova lei expande esse direito, incluindo a fisioterapia pelo SUS, quando houver indica\u00e7\u00e3o m\u00e9dica, tanto para mulheres quanto para homens em tratamento de c\u00e2ncer de mama.<\/p>\n<p style=\"text-align: justify;\">A norma teve origem na C\u00e2mara, com o projeto de lei\u00a0<a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/fichadetramitacao?idProposicao=2301541\" target=\"_blank\" rel=\"noopener\">3.436\/2021<\/a>, do ex-deputado Francisco Jr. (GO) e da deputada\u00a0<a class=\"parlLink ignore-hover\" href=\"https:\/\/radar.congressoemfoco.com.br\/parlamentar\/1204540\/perfil\" target=\"_blank\" rel=\"noopener\">Maria Rosas<\/a>\u00a0(Republicanos-SP). O texto recebeu parecer favor\u00e1vel em novembro de 2023.<\/p>\n<p style=\"text-align: justify;\">No Senado, o texto final foi aprovado em outubro deste ano, com parecer favor\u00e1vel do senador\u00a0<a class=\"parlLink ignore-hover\" href=\"https:\/\/radar.congressoemfoco.com.br\/parlamentar\/26027\/perfil\" target=\"_blank\" rel=\"noopener\">Mecias de Jesus<\/a>\u00a0(Republicanos-RR) na Comiss\u00e3o de Assuntos Sociais. Segundo o relator, a fisioterapia \u00e9 fundamental para a preven\u00e7\u00e3o e o tratamento de sequelas da cirurgia.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><strong>&#8220;A medida fortalece a pol\u00edtica p\u00fablica de aten\u00e7\u00e3o oncol\u00f3gica e valoriza uma abordagem mais humanizada e eficaz no tratamento do c\u00e2ncer de mama.&#8221;<\/strong><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Tratamento \u00e9 condicionado \u00e0 realiza\u00e7\u00e3o de procedimento cir\u00fargico de remo\u00e7\u00e3o parcial ou total da mama. O presidente da Rep\u00fablica em exerc\u00edcio, Geraldo Alckmin, sancionou a Lei\u00a015.267\/2025, que assegura a assist\u00eancia fisioterap\u00eautica para pacientes que passaram por mastectomia. A medida determina que o Sistema \u00danico de Sa\u00fade (SUS) ofere\u00e7a fisioterapia \u00e0s pessoas submetidas ao procedimento cir\u00fargico [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":126563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4381,71],"tags":[6651,658,7184,7183,555],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/126562"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=126562"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/126562\/revisions"}],"predecessor-version":[{"id":126564,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/126562\/revisions\/126564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/126563"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=126562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=126562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=126562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}