{"id":125960,"date":"2025-10-10T05:40:05","date_gmt":"2025-10-10T08:40:05","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=125960"},"modified":"2025-10-10T05:40:05","modified_gmt":"2025-10-10T08:40:05","slug":"mais-de-177-mil-familias-terao-que-devolver-auxilio-emergencial-recebido-indevidamente","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2025\/10\/10\/mais-de-177-mil-familias-terao-que-devolver-auxilio-emergencial-recebido-indevidamente\/","title":{"rendered":"Mais de 177 mil fam\u00edlias ter\u00e3o que devolver Aux\u00edlio Emergencial recebido indevidamente"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Notificados devem acessar o site VEJAE para consultar pend\u00eancias, apresentar defesa ou parcelar o pagamento em at\u00e9 60 vezes, sem cobran\u00e7a de juros ou multa<\/strong><\/p>\n<div id=\"js-text-clipboard\" class=\"notice-content__show js-notice-expand js-permit-copy auto-height\">\n<p style=\"text-align: justify;\">Desde mar\u00e7o, o Minist\u00e9rio do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome (<a href=\"https:\/\/www.gov.br\/mds\/pt-br\">MDS<\/a>) est\u00e1 notificando fam\u00edlias que receberam indevidamente o Aux\u00edlio Emergencial pago durante a pandemia de Covid-19. Ao todo, 177,4 mil fam\u00edlias precisam devolver os valores \u00e0 Uni\u00e3o, somando um total de R$ 478,8 milh\u00f5es. As notifica\u00e7\u00f5es s\u00e3o enviadas por SMS, WhatsApp, e-mail e pelo aplicativo Notifica, priorizando os casos com valores mais altos ou maior capacidade de pagamento.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Est\u00e3o isentos da devolu\u00e7\u00e3o os benefici\u00e1rios do Bolsa Fam\u00edlia, as pessoas inscritas no Cadastro \u00danico, quem recebeu menos de R$ 1,8 mil e as fam\u00edlias com renda per capita de at\u00e9 dois sal\u00e1rios m\u00ednimos ou renda familiar total de at\u00e9 tr\u00eas sal\u00e1rios m\u00ednimos. Entre os motivos que geram cobran\u00e7a est\u00e3o v\u00ednculo de emprego formal, recebimento de benef\u00edcio previdenci\u00e1rio, renda acima do limite legal e duplicidade de pagamento.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">A coordenadora-geral de Pagamento e Controle do MDS, Raquel Ara\u00fajo, orienta que os notificados e aqueles que t\u00eam d\u00favidas acessem o site <a href=\"https:\/\/www.gov.br\/pt-br\/servicos\/consultar-a-situacao-do-auxilio-emergencial-no-vejae\" target=\"_blank\" rel=\"noopener\">VEJAE<\/a>, onde \u00e9 poss\u00edvel consultar a situa\u00e7\u00e3o e regularizar eventuais pend\u00eancias. Segundo ela, \u201cpara as pessoas que possuem pend\u00eancia, l\u00e1 est\u00e1 explicado o motivo da irregularidade, qual foi o apontamento feito, e o sistema permite o contradit\u00f3rio e a ampla defesa. Ent\u00e3o, a pessoa pode apresentar sua defesa, apresentar recurso ou at\u00e9 mesmo fazer diretamente o pagamento, que pode ser via PIX, cart\u00e3o de cr\u00e9dito ou boleto. Lembrando que pode ser parcelado em at\u00e9 60 vezes, com parcela m\u00ednima de R$ 50, sem cobran\u00e7a de juros ou multa\u201d.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">O prazo para pagamento ou in\u00edcio do parcelamento \u00e9 de at\u00e9 60 dias a partir da notifica\u00e7\u00e3o, enquanto a defesa pode ser apresentada em at\u00e9 30 dias. Caso a justificativa seja negada, o cidad\u00e3o ter\u00e1 45 dias para efetuar o pagamento ou recorrer.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Quem n\u00e3o quitar ou regularizar a d\u00edvida pode ter o nome inscrito na D\u00edvida Ativa da Uni\u00e3o, no Cadin e nos \u00f3rg\u00e3os de prote\u00e7\u00e3o ao cr\u00e9dito. O MDS refor\u00e7a que n\u00e3o envia links nem boletos por mensagens de celular, WhatsApp ou e-mail. Todas as consultas devem ser feitas exclusivamente pelo site oficial do minist\u00e9rio.<\/p>\n<h2 dir=\"ltr\">N\u00famero de fam\u00edlias notificadas por estado:<\/h2>\n<ul>\n<li><span aria-level=\"1\"><span role=\"presentation\">Acre (AC): 648 fam\u00edlias \u2014 R$ 1.657.788,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Alagoas (AL): 1.479 fam\u00edlias \u2014 R$ 3.704.551,50<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Amazonas (AM): 2.640 fam\u00edlias \u2014 R$ 6.706.815,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Amap\u00e1 (AP): 395 fam\u00edlias \u2014 R$ 983.784,00<\/span><\/span><\/li>\n<li><span style=\"color: #ff0000;\" aria-level=\"1\"><span role=\"presentation\">Bahia (BA): 7.349 fam\u00edlias \u2014 R$ 18.452.919,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Cear\u00e1 (CE): 3.786 fam\u00edlias \u2014 R$ 9.658.712,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Distrito Federal (DF): 2.168 fam\u00edlias \u2014 R$ 5.884.041,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Esp\u00edrito Santo (ES): 4.398 fam\u00edlias \u2014 R$ 11.679.842,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Goi\u00e1s (GO): 6.304 fam\u00edlias \u2014 R$ 16.604.904,50<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Maranh\u00e3o (MA): 2.659 fam\u00edlias \u2014 R$ 6.519.607,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Minas Gerais (MG): 21.186 fam\u00edlias \u2014 R$ 56.695.260,50<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Mato Grosso do Sul (MS): 2.655 fam\u00edlias \u2014 R$ 6.876.424,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Mato Grosso (MT): 3.628 fam\u00edlias \u2014 R$ 9.452.075,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Par\u00e1 (PA): 4.968 fam\u00edlias \u2014 R$ 12.832.999,50<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Para\u00edba (PB): 1.820 fam\u00edlias \u2014 R$ 4.668.997,50<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Pernambuco (PE): 3.826 fam\u00edlias \u2014 R$ 10.066.912,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Piau\u00ed (PI): 1.525 fam\u00edlias \u2014 R$ 3.769.245,50<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Paran\u00e1 (PR): 13.259 fam\u00edlias \u2014 R$ 35.996.054,82<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Rio de Janeiro (RJ): 13.266 fam\u00edlias \u2014 R$ 35.596.761,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Rio Grande do Norte (RN): 1.783 fam\u00edlias \u2014 R$ 4.628.690,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Rond\u00f4nia (RO): 1.275 fam\u00edlias \u2014 R$ 3.191.082,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Roraima (RR): 487 fam\u00edlias \u2014 R$ 1.262.057,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Rio Grande do Sul (RS): 8.762 fam\u00edlias \u2014 R$ 24.241.122,00<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Santa Catarina (SC): 9.680 fam\u00edlias \u2014 R$ 26.788.889,60<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Sergipe (SE): 1.178 fam\u00edlias \u2014 R$ 3.156.699,30<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">S\u00e3o Paulo (SP): 55.251 fam\u00edlias \u2014 R$ 155.047.839,85<\/span><\/span><\/li>\n<li><span aria-level=\"1\"><span role=\"presentation\">Tocantins (TO): 1.088 fam\u00edlias \u2014 R$ 2.762.525,00<\/span><\/span><\/li>\n<\/ul>\n<p><span aria-level=\"1\"><span role=\"presentation\">No total, 177.443 fam\u00edlias devem devolver R$ 478.895.958,19 aos cofres p\u00fablicos.<\/span><\/span><\/p>\n<p>As informa\u00e7\u00f5es s\u00e3o do Minist\u00e9rio do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome.<\/p>\n<\/div>\n<div class=\"notice-content__tags\"><a class=\"notice-content__tag\" href=\"\/noticias\/tag\/auxilio-emergencial\">#Aux\u00edlio emergencial<\/a><a class=\"notice-content__tag\" href=\"\/noticias\/tag\/brasil\">#Brasil<\/a><a class=\"notice-content__tag\" href=\"\/noticias\/tag\/economia\">#Economia<\/a><\/div>\n<p>Fonte: <a href=\"https:\/\/brasil61.com\/n\/mais-de-177-mil-familias-terao-que-devolver-auxilio-emergencial-recebido-indevidamente-bras2514892?email=paulonunes4@gmail.com&amp;utm_source=newsletter&amp;utm_medium=newsletter&amp;utm_campaign=newsletter\" target=\"_blank\" rel=\"noopener\">Brasil 61<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notificados devem acessar o site VEJAE para consultar pend\u00eancias, apresentar defesa ou parcelar o pagamento em at\u00e9 60 vezes, sem cobran\u00e7a de juros ou multa Desde mar\u00e7o, o Minist\u00e9rio do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome (MDS) est\u00e1 notificando fam\u00edlias que receberam indevidamente o Aux\u00edlio Emergencial pago durante a pandemia de Covid-19. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":125961,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[75,105],"tags":[6906,6907],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/125960"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=125960"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/125960\/revisions"}],"predecessor-version":[{"id":125962,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/125960\/revisions\/125962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/125961"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=125960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=125960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=125960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}