{"id":125945,"date":"2025-10-09T15:03:25","date_gmt":"2025-10-09T18:03:25","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=125945"},"modified":"2025-10-09T15:03:25","modified_gmt":"2025-10-09T18:03:25","slug":"mercado-do-povo-leva-comercio-e-renda-a-municipios-mais-vulneraveis","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2025\/10\/09\/mercado-do-povo-leva-comercio-e-renda-a-municipios-mais-vulneraveis\/","title":{"rendered":"Mercado do Povo leva com\u00e9rcio e renda a munic\u00edpios mais vulner\u00e1veis"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Ser\u00e3o 136 mercados municipais implantados em diversas regi\u00f5es do pa\u00eds para apoiar pequenos produtores e gerar emprego e renda<\/strong><\/p>\n<p style=\"text-align: justify;\">\nO programa que vai fortalecer o com\u00e9rcio local, apoiar agricultores familiares e pequenos produtores e ampliar o acesso da popula\u00e7\u00e3o a espa\u00e7os modernos e adequados de comercializa\u00e7\u00e3o, foi lan\u00e7ado, pelo\u00a0<strong>Minist\u00e9rio da Integra\u00e7\u00e3o e do Desenvolvimento Regional (<a href=\"https:\/\/www.gov.br\/mdr\/pt-br\" target=\"_blank\" rel=\"noopener\">MIDR<\/a>)<\/strong>, nesta quarta-feira (8). Intitulado \u201cMercado do Povo\u201d, a iniciativa coordenada pela\u00a0<strong>Secretaria Nacional de Pol\u00edticas de Desenvolvimento Regional e Territorial (SDR)\u00a0<\/strong>promete trazer dignidade a todo produtor rural.<\/p>\n<p style=\"text-align: justify;\">\u201cO Mercado do Povo \u00e9 a consolida\u00e7\u00e3o de toda uma pol\u00edtica p\u00fablica que apoia quem produz alimento no Brasil, do campo \u00e0 cidade, com cr\u00e9dito, orienta\u00e7\u00e3o, assist\u00eancia t\u00e9cnica, inova\u00e7\u00e3o e tecnologia\u201d, destacou o ministro Waldez G\u00f3es. \u201cEstamos oferecendo mais uma a\u00e7\u00e3o governamental que complementa as demais iniciativas de apoio aos produtores: um ambiente limpo, seguro e saud\u00e1vel de neg\u00f3cios, onde a agricultura familiar pode vender o que produz e abastecer as comunidades brasileiras\u201d, completou.<\/p>\n<p style=\"text-align: justify;\">O\u00a0<strong>Mercado do Povo<\/strong>\u00a0prev\u00ea a implanta\u00e7\u00e3o de 136 mercados municipais modulares em diversas regi\u00f5es do pa\u00eds, priorizando munic\u00edpios com baixos \u00edndices de desenvolvimento, maior vulnerabilidade socioecon\u00f4mica e d\u00e9ficit de infraestrutura. As estruturas pr\u00e9-fabricadas contam com lojas, lanchonetes, escrit\u00f3rios, sanit\u00e1rios e \u00e1reas de circula\u00e7\u00e3o, oferecendo condi\u00e7\u00f5es adequadas para dinamizar a economia local, apoiar arranjos produtivos regionais e ampliar a gera\u00e7\u00e3o de emprego e renda.<\/p>\n<p style=\"text-align: justify;\">O\u00a0<strong>secret\u00e1rio Nacional de Pol\u00edticas de Desenvolvimento Regional e Territorial, Daniel Fortunato<\/strong>, destacou o papel sustent\u00e1vel do projeto. \u201cO produtor agora vai ter um local limpinho, novo e moderno para vender o seu produto. Isso \u00e9 bom para gerar emprego e renda e cumprir os objetivos da nossa Pol\u00edtica Nacional de Desenvolvimento Regional, a\u00a0<strong>PNDR<\/strong>, que \u00e9 trabalhar diretamente na redu\u00e7\u00e3o das desigualdades. Faremos isso ajudando quem mais precisa e melhorando a qualidade de vida por meio da venda de seus produtos em um local digno\u201d, comentou. \u201cEsse mercado deixar\u00e1 sua marca na atual gest\u00e3o\u201d, acrescentou.<\/p>\n<p style=\"text-align: justify;\">Ao parabenizar a iniciativa, o\u00a0<strong>senador Marcelo Castro (MDB\/PI)<\/strong>\u00a0destacou a import\u00e2ncia do desenvolvimento regional aliado \u00e0 inclus\u00e3o dos pequenos produtores. \u201cO projeto Mercado do Povo segue a orienta\u00e7\u00e3o do presidente Lula de promover o desenvolvimento do pa\u00eds. O agroneg\u00f3cio brasileiro tem alcan\u00e7ado resultados hist\u00f3ricos, batendo recordes sucessivos: chegamos recentemente a 350,2 milh\u00f5es de toneladas. Mas queremos crescer com inclus\u00e3o, sem deixar ningu\u00e9m para tr\u00e1s. Queremos crescer cuidando dos pequenos, e essa proposta dos mercados populares vai justamente ao encontro da ideia de atender as pequenas cidades e os pequenos produtores\u201d, afirmou o senador.<\/p>\n<p style=\"text-align: justify;\">O evento tamb\u00e9m contou com a presen\u00e7a dos\u00a0<strong>deputados federais Hildo Rocha (MDB\/MA), Gisela Simona (Uni\u00e3o Brasil\/MT), Benes Leoc\u00e1dio (Uni\u00e3o Brasil\/RN), Cleber Verde (MDB\/MA), Patr\u00edcia Ferraz (PL\/AP), Marcon (PT\/RS) e Pedro Uczai (PT\/SC)<\/strong>, al\u00e9m do\u00a0<strong>deputado estadual Jo\u00e3o Madson (MDB\/PI)\u00a0<\/strong>e de representantes da sociedade civil.<\/p>\n<h2>Como aderir<\/h2>\n<p style=\"text-align: justify;\">Os munic\u00edpios interessados poder\u00e3o aderir ao programa por meio da<strong>\u00a0Ata de Registro de Pre\u00e7os (ARP)\u00a0<\/strong>conduzida pelo\u00a0<strong>MIDR<\/strong>, dentro do\u00a0<strong>Sistema de Registro de Pre\u00e7os (SRP)<\/strong>. Para isso, a prefeitura deve encaminhar of\u00edcio \u00e0\u00a0<strong>Assessoria Especial de Assuntos Parlamentares e Federativos (AESPAR)<\/strong>, indicando o modelo compat\u00edvel com a sua tipologia populacional. Os valores estimados variam conforme o porte do munic\u00edpio: de R$ 5,2 milh\u00f5es para cidades de at\u00e9 20 mil habitantes, chegando a R$ 20,5 milh\u00f5es para aquelas com popula\u00e7\u00e3o acima de 100 mil habitantes, sempre sujeitos \u00e0 an\u00e1lise de viabilidade t\u00e9cnica e or\u00e7ament\u00e1ria.<\/p>\n<p style=\"text-align: justify;\">A iniciativa tamb\u00e9m funcionar\u00e1 como um centro de dinamiza\u00e7\u00e3o econ\u00f4mica e social, integrando agricultores, empreendedores e comunidades em torno de um processo articulado de crescimento sustent\u00e1vel, alinhado \u00e0s pol\u00edticas de redu\u00e7\u00e3o de desigualdades e promo\u00e7\u00e3o da seguran\u00e7a alimentar.<\/p>\n<div class=\"notice-content__tags\"><a class=\"notice-content__tag\" href=\"https:\/\/brasil61.com\/noticias\/tag\/desenvolvimento-regional\">#Desenvolvimento regional<\/a><a class=\"notice-content__tag\" href=\"https:\/\/brasil61.com\/noticias\/tag\/mdr\">#MDR<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e3o 136 mercados municipais implantados em diversas regi\u00f5es do pa\u00eds para apoiar pequenos produtores e gerar emprego e renda O programa que vai fortalecer o com\u00e9rcio local, apoiar agricultores familiares e pequenos produtores e ampliar o acesso da popula\u00e7\u00e3o a espa\u00e7os modernos e adequados de comercializa\u00e7\u00e3o, foi lan\u00e7ado, pelo\u00a0Minist\u00e9rio da Integra\u00e7\u00e3o e do Desenvolvimento Regional [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":125946,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5056,71],"tags":[1048,5921,5920,6896],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/125945"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=125945"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/125945\/revisions"}],"predecessor-version":[{"id":125947,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/125945\/revisions\/125947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/125946"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=125945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=125945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=125945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}