{"id":125799,"date":"2025-10-02T01:07:03","date_gmt":"2025-10-02T04:07:03","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=125799"},"modified":"2025-10-02T01:07:03","modified_gmt":"2025-10-02T04:07:03","slug":"justica-tributaria-camara-aprova-isencao-de-ir-para-quem-ganha-ate-r-5-mil","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2025\/10\/02\/justica-tributaria-camara-aprova-isencao-de-ir-para-quem-ganha-ate-r-5-mil\/","title":{"rendered":"Justi\u00e7a tribut\u00e1ria: C\u00e2mara aprova isen\u00e7\u00e3o de IR para quem ganha at\u00e9 R$ 5 mil"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Ser\u00e3o mais de 26,6 milh\u00f5es de contribuintes isentos do Imposto de Renda, aproximadamente 65% dos declarantes<\/strong><\/p>\n<p style=\"text-align: justify;\">A C\u00e2mara dos Deputados aprovou nesta quarta-feira (1\u00ba), com 493 votos favor\u00e1veis e nenhum contr\u00e1rio,\u00a0o texto-base do projeto de Lei (PL) 1.087\/2025, que prev\u00ea isen\u00e7\u00e3o de Imposto de Renda (IR) para pessoas f\u00edsicas com renda mensal de at\u00e9 R$ 5 mil\u00a0e desconto para quem ganha at\u00e9 R$ 7.350 mensais.<\/p>\n<p style=\"text-align: justify;\">A proposta, encaminhada pelo governo federal, ainda\u00a0ter\u00e1 que ser aprovada\u00a0no Senado, antes da san\u00e7\u00e3o\u00a0pelo presidente Luiz In\u00e1cio Lula da Silva para entrar em vigor.<\/p>\n<p style=\"text-align: justify;\">A redu\u00e7\u00e3o do IR foi uma promessa de campanha de Lula em 2022. Enviado para a C\u00e2mara em mar\u00e7o, o texto foi aprovado em uma comiss\u00e3o especial que analisou o texto.<\/p>\n<p style=\"text-align: justify;\">Atualmente, s\u00e3o isentos do imposto quem ganha\u00a0at\u00e9 R$ 3.036. O projeto determina que,\u00a0em 2026, as pessoas que ganham at\u00e9 R$ 5 mil, ter\u00e3o um desconto mensal de at\u00e9 R$ 312,89, de modo que o imposto devido seja zero.\u00a0J\u00e1 quem ganha de R$ 5.000,01 at\u00e9 R$ 7.350,00, o desconto ser\u00e1 de R$ 978,62.<\/p>\n<p style=\"text-align: justify;\">Segundo o governo, com a aprova\u00e7\u00e3o da proposta,\u00a0ser\u00e3o beneficiados com a isen\u00e7\u00e3o mais de 26,6 milh\u00f5es de contribuintes, em 2026.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Compensa\u00e7\u00e3o<\/strong><\/h2>\n<p style=\"text-align: justify;\">Para compensar a isen\u00e7\u00e3o, cujo custo est\u00e1 estimado ser\u00e1 de\u00a0R$ 25,8 bilh\u00f5es aos cofres p\u00fablicos, o projeto prev\u00ea a tributa\u00e7\u00e3o das pessoas com rendimentos acima de R$ 600 mil por ano, com uma al\u00edquota progressiva de at\u00e9 10%.<\/p>\n<p style=\"text-align: justify;\">A al\u00edquota m\u00e1xima incidir\u00e1 para quem recebe anualmente a partir de R$ 1,2 milh\u00e3o. Al\u00e9m disso, ela n\u00e3o ser\u00e1 aplicada para quem j\u00e1 paga a al\u00edquota m\u00e1ximo do IR, que \u00e9 de 27,5%.<\/p>\n<p style=\"text-align: justify;\">Segundo o Minist\u00e9rio da Fazenda, a medida atingir\u00e1 cerca de 140 mil pessoas, 0,13% dos contribuintes, que hoje pagam, em m\u00e9dia, apenas 2,54% de Imposto de Renda.<\/p>\n<p style=\"text-align: justify;\">O relator do projeto, deputado Arthur Lira (PP-AL), estima que haver\u00e1 uma sobra de R$ 12,7 bilh\u00f5es at\u00e9 2027 com a taxa\u00e7\u00e3o. Em seu parecer, Lira destinou esses recursos para compensar a redu\u00e7\u00e3o da al\u00edquota da Contribui\u00e7\u00e3o sobre Bens e Servi\u00e7os (CBS), institu\u00edda pela Reforma Tribut\u00e1ria.<\/p>\n<p style=\"text-align: justify;\">\u201c\u00c9 importante ressaltar que esse projeto vai atender diretamente a 15,5 milh\u00f5es de\u00a0pessoas no pa\u00eds. Esse projeto \u00e9 fruto de uma base de c\u00e1lculo de quase R$ 227 bilh\u00f5es, que \u00e9 apurado no imposto de renda no Brasil. E estamos discutindo uma ren\u00fancia de receita, no primeiro ano de, R$ 25,4 bilh\u00f5es, portanto 10% do valor total do imposto de renda pago por todos os brasileiros\u201d, disse.<\/p>\n<h2><strong>Justi\u00e7a tribut\u00e1ria<\/strong><\/h2>\n<p>O deputado Carlos Zarattini (PT-SP) disse que com o projeto, o pa\u00eds come\u00e7a a fazer justi\u00e7a tribut\u00e1ria.<\/p>\n<p style=\"text-align: justify;\">\u201cNosso pa\u00eds \u00e9 um pa\u00eds da desigualdade, \u00e9 um pa\u00eds onde uma \u00ednfima minoria det\u00e9m a maior parte da riqueza enquanto a maioria do povo brasileiro vive em dif\u00edceis condi\u00e7\u00f5es. A justi\u00e7a tribut\u00e1ria precisa ser feita e esse projeto que mira na justi\u00e7a tribut\u00e1ria. Uma justi\u00e7a que pode reduzir as desigualdades, que pode fazer com que as pessoas de menor renda e a classe m\u00e9dia brasileira possam ter uma capacidade de consumo melhor, uma capacidade de viver melhor a sua vida\u201d, afirmou.<\/p>\n<p style=\"text-align: justify;\">A deputada Fernanda Melchiona (PSOL-RS) lembrou que a iniciativa foi pautada ap\u00f3s as manifesta\u00e7\u00f5es de setembro contra a proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) das prerrogativas, a chamada PEC da Blindagem e o projeto de anistia aos presos pelos atos golpistas de 8 de janeiro de 2023.<\/p>\n<p style=\"text-align: justify;\">\u201cEsse projeto \u00e9 muito importante, milh\u00f5es de brasileiros ser\u00e3o impactados com a redu\u00e7\u00e3o imediata do imposto de renda e com a redu\u00e7\u00e3o para quem ganha entre R$ 5 mil\u00a0e R$ 7 mil e, ao mesmo tempo, um imposto m\u00ednimo que vai ser cobrado dos super-ricos\u201d, completou.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Cr\u00edticas<\/strong><\/h2>\n<p style=\"text-align: justify;\">A iniciativa foi objeto de cr\u00edticas de alguns parlamentares. O deputado Gilson Marques (Novo-SC) disse que os recursos n\u00e3o ir\u00e3o para os mais pobres e criticou a tributa\u00e7\u00e3o de lucros e dividendos.<\/p>\n<p style=\"text-align: justify;\">\u201cVamos cobrar dos mais ricos, s\u00e3o s\u00f3 140 mil pessoas para dar para os mais pobres. Isso \u00e9 mentira! Esse dinheiro n\u00e3o vai para os mais pobres, vai para os pol\u00edticos. E \u00e9 melhor que esse dinheiro ficasse ainda que com os mais ricos, porque s\u00e3o eles que empregam, compram as m\u00e1quinas, fazem os produtos\u201d, argumentou.<\/p>\n<p style=\"text-align: justify;\">O texto determina que\u00a0o emprego ou a entrega de lucros e dividendos por uma mesma pessoa jur\u00eddica a uma mesma pessoa f\u00edsica residente no Brasil em montante superior a R$ 50 mil mensais ficar\u00e1 sujeito \u00e0 reten\u00e7\u00e3o na fonte do IRPF\u00a0\u00e0 al\u00edquota de 10% sobre o total do valor pago, creditado, empregado ou entregue.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o ficar\u00e3o sujeitos \u00e0 incid\u00eancia do imposto sobre a renda na fonte os lucros e dividendos relativos a resultados apurados at\u00e9 o ano-calend\u00e1rio de 2025, e cuja distribui\u00e7\u00e3o tenha sido aprovada at\u00e9 31 de dezembro de 2025.<\/p>\n<p style=\"text-align: justify;\">Mais cedo, o deputado Bibo Nunes (PL-RS) classificou a medida como &#8220;populista&#8221;, apesar de concordar que seja necess\u00e1ria. &#8220;\u00c9 s\u00f3 jogada pol\u00edtica, clientelismo, por que Lula n\u00e3o apresentou isso no primeiro ano [de governo]?\u201d, questionou.<\/p>\n<p style=\"text-align: justify;\">Para o deputado Luiz Carlos Hauly (Pode-PR), a proposta \u00e9 uma medida eleitoral, mas sem reparo estrutural. \u201cIsso resolveu o problema do imposto dos pobres? N\u00e3o. O pobre continua pagando a mais alta carga tribut\u00e1ria do mundo. Isso \u00e9 engana\u00e7\u00e3o. N\u00e3o tem nada a ver com a reestrutura\u00e7\u00e3o do sistema de carga tribut\u00e1ria sobre os pobres\u201d, disse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e3o mais de 26,6 milh\u00f5es de contribuintes isentos do Imposto de Renda, aproximadamente 65% dos declarantes A C\u00e2mara dos Deputados aprovou nesta quarta-feira (1\u00ba), com 493 votos favor\u00e1veis e nenhum contr\u00e1rio,\u00a0o texto-base do projeto de Lei (PL) 1.087\/2025, que prev\u00ea isen\u00e7\u00e3o de Imposto de Renda (IR) para pessoas f\u00edsicas com renda mensal de at\u00e9 R$ [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":125800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[78,105],"tags":[6801,1645,6800],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/125799"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=125799"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/125799\/revisions"}],"predecessor-version":[{"id":125801,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/125799\/revisions\/125801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/125800"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=125799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=125799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=125799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}