{"id":123328,"date":"2025-05-16T04:49:00","date_gmt":"2025-05-16T07:49:00","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=123328"},"modified":"2025-05-16T04:49:00","modified_gmt":"2025-05-16T07:49:00","slug":"gripe-e-principal-causa-de-mortes-por-srag-em-idosos-alerta-fiocruz","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2025\/05\/16\/gripe-e-principal-causa-de-mortes-por-srag-em-idosos-alerta-fiocruz\/","title":{"rendered":"Gripe \u00e9 principal causa de mortes por SRAG em idosos, alerta Fiocruz"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Doen\u00e7a tamb\u00e9m aparece entre as tr\u00eas principais causas de \u00f3bitos por SRAG em crian\u00e7as<\/strong><\/p>\n<div class=\"materia-conteudo\">\n<div class=\"materia\">\n<div class=\"conteudo_post\">\n<p style=\"text-align: justify;\">A gripe causada pelo v\u00edrus influenza A se tornou a principal respons\u00e1vel por mortes por S\u00edndrome Respirat\u00f3ria Aguda Grave (SRAG) entre idosos no Brasil, segundo alerta divulgado nesta quinta-feira (15) pelo boletim InfoGripe, da Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz). A doen\u00e7a tamb\u00e9m aparece entre as tr\u00eas principais causas de \u00f3bitos por SRAG em crian\u00e7as.<\/p>\n<p style=\"text-align: justify;\">O boletim aponta um aumento nas hospitaliza\u00e7\u00f5es por influenza A em diversas regi\u00f5es do pa\u00eds, com n\u00edveis moderados a altos de incid\u00eancia especialmente nos estados do Centro-Sul, al\u00e9m de registros preocupantes tamb\u00e9m no Norte e no Nordeste.<\/p>\n<p style=\"text-align: justify;\">J\u00e1 em alguns estados do Centro-Oeste e Sudeste, o n\u00famero de casos de SRAG em crian\u00e7as pequenas associados ao V\u00edrus Sincicial Respirat\u00f3rio (VSR) come\u00e7a a desacelerar ou at\u00e9 apresentar sinais de queda. Mesmo assim, a pesquisadora Tatiana Portella alerta que ainda n\u00e3o \u00e9 hora de relaxar os cuidados. \u201cA incid\u00eancia continua alta ou moderada\u201d, pontua.<\/p>\n<p style=\"text-align: justify;\">A Fiocruz destaca ainda que, entre as crian\u00e7as pequenas, a mortalidade por SRAG se aproxima da observada em idosos. Nessa faixa et\u00e1ria, o VSR continua sendo o principal causador de mortes, seguido pelo rinov\u00edrus e pela influenza A. J\u00e1 entre os idosos, a gripe lidera como causa de \u00f3bitos, seguida pela Covid-19.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Doen\u00e7a tamb\u00e9m aparece entre as tr\u00eas principais causas de \u00f3bitos por SRAG em crian\u00e7as A gripe causada pelo v\u00edrus influenza A se tornou a principal respons\u00e1vel por mortes por S\u00edndrome Respirat\u00f3ria Aguda Grave (SRAG) entre idosos no Brasil, segundo alerta divulgado nesta quinta-feira (15) pelo boletim InfoGripe, da Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz). A doen\u00e7a tamb\u00e9m [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":123329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[29,71],"tags":[5589,5526,4017,938],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/123328"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=123328"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/123328\/revisions"}],"predecessor-version":[{"id":123330,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/123328\/revisions\/123330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/123329"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=123328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=123328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=123328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}