{"id":120799,"date":"2024-08-24T18:26:39","date_gmt":"2024-08-24T21:26:39","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=120799"},"modified":"2024-08-24T18:26:39","modified_gmt":"2024-08-24T21:26:39","slug":"em-cicero-dantas-governo-do-estado-inaugura-obras-e-sanciona-lei-estadual-da-agroecologia","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2024\/08\/24\/em-cicero-dantas-governo-do-estado-inaugura-obras-e-sanciona-lei-estadual-da-agroecologia\/","title":{"rendered":"Em C\u00edcero Dantas, Governo do Estado inaugura obras e sanciona Lei Estadual da Agroecologia"},"content":{"rendered":"<p style=\"text-align: justify;\">O incentivo \u00e0 produ\u00e7\u00e3o de alimentos agroecol\u00f3gicos e a garantia da seguran\u00e7a alimentar de homens e mulheres do campo, al\u00e9m de investimentos robustos em desenvolvimento rural, estiveram entre as a\u00e7\u00f5es apresentadas pelo governador Jer\u00f4nimo Rodrigues, neste s\u00e1bado (24), durante a IV Feira Territorial da Agricultura Familiar, no munic\u00edpio de C\u00edcero Dantas, nordeste baiano. O evento, promovido pela Associa\u00e7\u00e3o Regional de Conviv\u00eancia Apropriada ao Semi\u00e1rido (Arcas) com apoio do Governo do Estado, reuniu 200 expositores fortalecendo os empreendimentos produtivos.<\/p>\n<div style=\"text-align: justify;\">Recebido com um caf\u00e9 da manh\u00e3 na sede da Pastoral Rural, que re\u00fane crist\u00e3os, fam\u00edlias e trabalhadores rurais sem terra, Jer\u00f4nimo Rodrigues autorizou a publica\u00e7\u00e3o da Lei Estadual n\u00b0 14.564, de 16\/05\/2023, que institui a Pol\u00edtica Estadual de Agroecologia e Produ\u00e7\u00e3o Org\u00e2nica (Peapo), no Di\u00e1rio Oficial do Estado da Bahia (D.O) da pr\u00f3xima ter\u00e7a-feira (27).<\/div>\n<div style=\"text-align: justify;\">\u201cQuando colocamos alimentos da agroecologia no prato, estamos fortalecendo a agricultura familiar e incentivando a pesquisa e educa\u00e7\u00e3o rural. Esse foi o meu primeiro Projeto de Lei encaminhado \u00e0 Assembleia Legislativa (Alba), que criou condi\u00e7\u00f5es para que a agroecologia fosse debatida. O objetivo da Peapo, constru\u00edda por agricultores, organiza\u00e7\u00f5es e movimentos sociais, \u00e9 promover mais qualidade de vida para a popula\u00e7\u00e3o das cidades e do campo por meio da oferta de \u00e1gua de qualidade, consumo de alimentos saud\u00e1veis e uso sustent\u00e1vel de recursos naturais na perspectiva da seguran\u00e7a alimentar e nutricional\u201d, explicou Jer\u00f4nimo Rodrigues.<\/div>\n<div style=\"text-align: justify;\">No \u00e2mbito da seguran\u00e7a nutricional, o coordenador do Bahia Sem Fome, Tiago Pereira, enfatizou que a lei vai permitir o di\u00e1logo entre a agroecologia e o programa. \u201cEsse processo vai nos permitir ter mais or\u00e7amento, mais a\u00e7\u00f5es e projetos, que de certa forma v\u00e3o ajudar na constru\u00e7\u00e3o do pa\u00eds. Significa uma sociedade com comida saud\u00e1vel no prato, com produ\u00e7\u00e3o de alimentos, gera\u00e7\u00e3o de trabalho e renda\u201d, pontuou.<\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">Uma das representantes da Pastoral Rural, fundadora da Arcas, a Irm\u00e3 Gabriela Canavesio, afirmou que o ato foi uma conquista hist\u00f3rica para as fam\u00edlias do campo, quilombolas e comunidades tradicionais, em especial \u00e0s dos Territ\u00f3rios de Identidade do Semi\u00e1rido Nordeste II, S\u00e3o Francisco e Litoral Norte. \u201cA Pastoral Rural se dedica \u00e0s pessoas que moram na zona rural e que n\u00e3o tem acesso a direitos b\u00e1sicos. \u00c9 um trabalho dif\u00edcil, de resist\u00eancia e paci\u00eancia. A nossa caminhada j\u00e1 dura 50 anos e naquela \u00e9poca, ningu\u00e9m imaginava que ter\u00edamos condi\u00e7\u00f5es de dialogar com o Governo do Estado t\u00e3o de perto. Essa \u00e9 mais uma prova do que\u00a0 significa governar para o povo, cuidar de gente. S\u00e3o propostas maravilhosas, de uma sabedoria incr\u00edvel\u201d, contou emocionada.<\/div>\n<div style=\"text-align: justify;\">Para o titular da Secretaria de Desenvolvimento Rural (SDR), Osni Cardoso, esse projeto \u201csimboliza a produ\u00e7\u00e3o de alimento limpo, sem agrot\u00f3xico e o respeito \u00e0 emerg\u00eancia clim\u00e1tica. \u00c9 a defesa do nosso planeta e a perman\u00eancia do homem e da mulher do campo com qualidade de vida\u201d.<\/div>\n<div style=\"text-align: justify;\"><b>Mais estrutura<\/b><\/div>\n<div style=\"text-align: justify;\">Ainda como parte das a\u00e7\u00f5es do Governo do Estado, atrav\u00e9s da SDR, foram entregues em C\u00edcero Dantas, a reforma do Mercado Municipal com 51 boxes e 60 barracas de feira livre, al\u00e9m de unidades de beneficiamento de frutas, de mandioca e entreposto de mel para distritos. O investimento total foi de R$ 6 milh\u00f5es.<\/div>\n<div style=\"text-align: justify;\">Dono de um dos boxes do mercado, o lavrador Edvaldo Vitor aprovou o novo espa\u00e7o. \u201cAqui mudou 100%. Estava ruim demais, caindo aos peda\u00e7os, tudo sujo. E agora botou cer\u00e2mica, piso, j\u00e1 modificou o telhado. As vendas at\u00e9 aumentaram. Bom demais\u201d, comemorou.<\/div>\n<div style=\"text-align: justify;\">A Pastoral Rural ainda ganhou 90 barracas de feira livre, tratores com implementos e equipamentos agr\u00edcolas e kits para apicultura. A Associa\u00e7\u00e3o dos Trabalhadores Rurais do Assentamento Mundo Novo, em Tucano, recebeu um caminh\u00e3o pipa. \u201cDurante o ver\u00e3o precisamos colocar \u00e1gua nos lotes mais distantes que ainda n\u00e3o t\u00eam \u00e1gua encanada, ent\u00e3o esse pipa \u00e9 muito importante para o acesso \u00e0 \u00e1gua limpa. Ser\u00e3o 15 fam\u00edlias beneficiadas\u201d, contou o presidente da entidade, Jos\u00e9 Roberto Almeida,.<\/div>\n<div style=\"text-align: justify;\"><b>Outros atos<\/b><\/div>\n<div style=\"text-align: justify;\">Obras de pavimenta\u00e7\u00e3o foram entregues em 24 km do trecho que compreende a BR-110 ao distrito de Caxias e na BA-220, entre C\u00edcero Dantas e S\u00e3o Jo\u00e3o da Fortaleza. Foram investidos R$ 56 milh\u00f5es. \u00a0A cidade tamb\u00e9m recebeu pavimenta\u00e7\u00e3o em paralelep\u00edpedos nos bairros de Mangueira e Bela Vista. Ainda foi assinada uma ordem de servi\u00e7o para a pavimenta\u00e7\u00e3o da travessia urbana do munic\u00edpio, na ordem de R$ 5,2 milh\u00f5es.<\/div>\n<div style=\"text-align: justify;\">A oferta de \u00e1gua tratada e de qualidade chegou \u00e0s localidades de Boi Morto, Cirino, Sap\u00e9, Inchuir, Chapada da Lagoa Grande e Serra Vermelha. O governador tamb\u00e9m autorizou a perfura\u00e7\u00e3o de po\u00e7os em C\u00edcero Dantas e Banza\u00ea.<\/div>\n<div><\/div>\n<div><b><i>Rep\u00f3rter: Sim\u00f4nica Capristano<\/i><\/b><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O incentivo \u00e0 produ\u00e7\u00e3o de alimentos agroecol\u00f3gicos e a garantia da seguran\u00e7a alimentar de homens e mulheres do campo, al\u00e9m de investimentos robustos em desenvolvimento rural, estiveram entre as a\u00e7\u00f5es apresentadas pelo governador Jer\u00f4nimo Rodrigues, neste s\u00e1bado (24), durante a IV Feira Territorial da Agricultura Familiar, no munic\u00edpio de C\u00edcero Dantas, nordeste baiano. O evento, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":120800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[130,105],"tags":[1481,4654,437,4655,4653],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/120799"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=120799"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/120799\/revisions"}],"predecessor-version":[{"id":120801,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/120799\/revisions\/120801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/120800"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=120799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=120799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=120799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}