{"id":117567,"date":"2024-01-13T13:41:12","date_gmt":"2024-01-13T16:41:12","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=117567"},"modified":"2024-01-13T13:41:12","modified_gmt":"2024-01-13T16:41:12","slug":"ministro-dos-transportes-coloca-fiol-ii-como-prioritario-em-2024-ligacao-entre-fiol-iii-e-mato-grosso-entra-em-estudo-para-concessao","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2024\/01\/13\/ministro-dos-transportes-coloca-fiol-ii-como-prioritario-em-2024-ligacao-entre-fiol-iii-e-mato-grosso-entra-em-estudo-para-concessao\/","title":{"rendered":"Ministro dos Transportes coloca FIOL II como priorit\u00e1rio em 2024.Liga\u00e7\u00e3o entre FIOL III e Mato Grosso entra em estudo para concess\u00e3o"},"content":{"rendered":"<p style=\"text-align: justify;\">O Minist\u00e9rio dos Transportes colocou como trechos de priorit\u00e1rios de ferrovia para este ano, a liga\u00e7\u00e3o\u00a0 entre Caetit\u00e9 \u00a0e Barreiras, da Fiol II, com 485 km. O trecho j\u00e1 tem 66% da obra conclu\u00edda e dois trechos em execu\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">A informa\u00e7\u00e3o \u00e9 o do Ministro dos Transportes, Renan Flho, em entrevista coletiva na tarde desta quarta-feira (10).<\/p>\n<p style=\"text-align: justify;\">O ministro tamb\u00e9m colocou como prioridades da pasta para este ano a liga\u00e7\u00e3o ferrovi\u00e1ria entre \u00a0Mara Rosa (GO) e \u00c1gua Boa (MT), da Fico, com 363 km e um novo trecho da ferrovia Transnordestina, de Salgueiro at\u00e9 o Porto de Suape.<\/p>\n<p style=\"text-align: justify;\">Na coletiva, Renan colocou o trecho da Fiol I, entre Caetit\u00e9 e Ilh\u00e9us como equacionado, j\u00e1 que h\u00e1 previs\u00e3o da Bamin concluir o trecho em 2027.<\/p>\n<p style=\"text-align: justify;\">A apresenta\u00e7\u00e3o do Minist\u00e9rio ainda garantiu que o Plano Nacional de Ferrovias ser\u00e1 apresentado no primeiro semestre deste ano.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, chamou aten\u00e7\u00e3o na apresenta\u00e7\u00e3o do ministro a liga\u00e7\u00e3o entre Lucas do Rio Verde, no Mato Grosso, e \u00a0Caetit\u00e9 na Bahia. \u00a0O governo estuda incluir no pacote da Fiol um trecho adicional da Fico (a Fico 2), que iria de \u00c1gua Boa at\u00e9 Lucas do Rio Verde (MT). O portal Bahia Econ\u00f4mica j\u00e1 entrou em contato com o MT para ter maiores informa\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">O governo quer ainda dar prosseguimento aos seguintes estudos para concess\u00f5es:<\/p>\n<p style=\"text-align: justify;\">Corredor Arco-Norte (Ferrogr\u00e3o)<\/p>\n<p style=\"text-align: justify;\">EF-118 (Rio-Vit\u00f3ria)<\/p>\n<p style=\"text-align: justify;\">Corredor Leste \u2013 Oeste (Lucas do Rio Verde \u2013 Caetit\u00e9)<\/p>\n<p style=\"text-align: justify;\">Transporte Ferrovi\u00e1rio de Passageiros \u2013 6 trechos<\/p>\n<p style=\"text-align: justify;\">Malha Centro-Leste (FCA),<\/p>\n<p style=\"text-align: justify;\">Malha Nordeste (FTL), Malha Sul (Rumo) e Ferrovia Tereza Cristina (FTC)<\/p>\n<p style=\"text-align: justify;\">Trem Intercidades (TIC)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio dos Transportes colocou como trechos de priorit\u00e1rios de ferrovia para este ano, a liga\u00e7\u00e3o\u00a0 entre Caetit\u00e9 \u00a0e Barreiras, da Fiol II, com 485 km. O trecho j\u00e1 tem 66% da obra conclu\u00edda e dois trechos em execu\u00e7\u00e3o. A informa\u00e7\u00e3o \u00e9 o do Ministro dos Transportes, Renan Flho, em entrevista coletiva na tarde desta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":117568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[22,105],"tags":[734,3331,3332,3333,3330,740],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/117567"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=117567"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/117567\/revisions"}],"predecessor-version":[{"id":117569,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/117567\/revisions\/117569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/117568"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=117567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=117567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=117567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}