{"id":113291,"date":"2023-03-03T05:34:51","date_gmt":"2023-03-03T08:34:51","guid":{"rendered":"https:\/\/www.blogdopaulonunes.com\/v5\/?p=113291"},"modified":"2023-03-02T20:55:33","modified_gmt":"2023-03-02T23:55:33","slug":"area-social-lidera-investimentos-da-bahia-entre-2015-e-2022-e-deve-seguir-como-prioridade-do-governo","status":"publish","type":"post","link":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/2023\/03\/03\/area-social-lidera-investimentos-da-bahia-entre-2015-e-2022-e-deve-seguir-como-prioridade-do-governo\/","title":{"rendered":"\u00c1rea social lidera investimentos da Bahia entre 2015 e 2022 e deve seguir como prioridade do Governo"},"content":{"rendered":"<div class=\"\">\n<div id=\":t3\" class=\"ii gt\">\n<div id=\":w9\" class=\"a3s aiL msg-4345799774227188245\">\n<div dir=\"ltr\">\n<div>\n<div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Foram destinados R$ 7,7 bilh\u00f5es no per\u00edodo para Educa\u00e7\u00e3o, Sa\u00fade e Seguran\u00e7a P\u00fablica. No total investido, a Bahia manteve o segundo lugar entre os estados no per\u00edodo<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">A \u00e1rea social liderou os investimentos do governo baiano entre 2015 e 2022, com um total de R$ 7,7 bilh\u00f5es destinados a Educa\u00e7\u00e3o, Sa\u00fade e Seguran\u00e7a P\u00fablica. Em seguida, ficaram os investimentos em Urbanismo (R$ 6,2 bilh\u00f5es), Transporte (R$ 5,2 bilh\u00f5es), Saneamento (R$ 2,7 bilh\u00f5es) e Agricultura (R$ 1,9 bilh\u00e3o). Com um desembolso total de R$ 27,5 bilh\u00f5es, a Bahia manteve o segundo lugar no per\u00edodo em investimentos p\u00fablicos liquidados no \u00e2mbito dos estados, ficando atr\u00e1s apenas de S\u00e3o Paulo, de acordo com informa\u00e7\u00f5es da Secretaria do Tesouro Nacional (STN).<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">O ranking dos investimentos considera os n\u00fameros relativos \u00e0s administra\u00e7\u00f5es estaduais que acabam de ser consolidados pela STN por meio do Sistema de Informa\u00e7\u00f5es Cont\u00e1beis e Fiscais do Setor P\u00fablico Brasileiro \u2013 Siconfi.<\/div>\n<figure id=\"attachment_113295\" aria-describedby=\"caption-attachment-113295\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"size-full wp-image-113295\" src=\"https:\/\/www.blogdopaulonunes.com\/v5\/wp-content\/uploads\/2023\/03\/Colegio-Integral7.png\" alt=\"\" width=\"300\" height=\"160\" \/><figcaption id=\"caption-attachment-113295\" class=\"wp-caption-text\">Col\u00e9gio de Tempo Integral: Imagem Jo\u00e1 Souza<\/figcaption><\/figure>\n<div><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">A prioridade para as \u00e1reas sociais \u00e9 uma diretriz a ser intensificada a partir de agora pelo Estado da Bahia por determina\u00e7\u00e3o do governador Jer\u00f4nimo Rodrigues, afirma o secret\u00e1rio da Fazenda do Estado, Manoel Vit\u00f3rio. \u201cA orienta\u00e7\u00e3o expressa do governador \u00e9 que o Estado, al\u00e9m de atuar fortemente no combate \u00e0 fome em parceria com o governo federal, reforce ainda mais os investimentos nas \u00e1reas sociais\u201d, afirma. \u201cVamos ent\u00e3o dar ainda mais prioridade a estes temas que j\u00e1 eram enfatizados nas gest\u00f5es anteriores, de Jaques Wagner e Rui Costa, como expresso nos n\u00fameros relativos aos investimentos\u201d.<\/div>\n<div>\n<figure id=\"attachment_113293\" aria-describedby=\"caption-attachment-113293\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"size-full wp-image-113293\" src=\"https:\/\/www.blogdopaulonunes.com\/v5\/wp-content\/uploads\/2023\/03\/Hospital-Metropolitano-imagem-Fernado-Vivas.png\" alt=\"\" width=\"300\" height=\"200\" \/><figcaption id=\"caption-attachment-113293\" class=\"wp-caption-text\">Hospital Metropolitano-imagem-Fernando Vivas<\/figcaption><\/figure>\n<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Outra diretriz do governador neste in\u00edcio de gest\u00e3o \u00e9 a manuten\u00e7\u00e3o do equil\u00edbrio fiscal como forma de assegurar a continuidade das pol\u00edticas p\u00fablicas voltadas para o atendimento \u00e0s principais demandas da popula\u00e7\u00e3o, explica Vit\u00f3rio. \u201cEsta agenda tem como ponto de partida a combina\u00e7\u00e3o entre iniciativas de qualidade do gasto, moderniza\u00e7\u00e3o do fisco e combate \u00e0 sonega\u00e7\u00e3o, e dever\u00e1 integrar ainda outras iniciativas voltadas \u00e0 promo\u00e7\u00e3o do desenvolvimento\u201d, afirma.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><b>Ranking dos investimentos<\/b><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">De acordo com os dados do Siconfi, a Bahia foi superada no per\u00edodo 2015-2022 apenas por S\u00e3o Paulo, que registrou um total de R$ 73,9 bilh\u00f5es em investimentos liquidados. Tendo desembolsado quase tr\u00eas vezes mais que o governo baiano, S\u00e3o Paulo, no entanto, investiu proporcionalmente menos, j\u00e1 que possui or\u00e7amento cinco vezes maior.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00a0Rio de Janeiro, com R$ 20,5 bilh\u00f5es, Minas Gerais, com R$ 20,2 bilh\u00f5es, e Cear\u00e1, com R$ 18,5 bilh\u00f5es, completam a linha de frente do ranking de investimentos liquidados desde 2015. A lista dos dez estados que mais investiram inclui ainda Par\u00e1, que investiu R$ 17,9 bilh\u00f5es, Santa Catarina (R$ 15,1 bilh\u00f5es), Paran\u00e1 (R$ 14,2 bilh\u00f5es), Maranh\u00e3o (R$ 10,4 bilh\u00f5es) e Mato Grosso (R$ 10,15 bilh\u00f5es).<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><b>Mais infraestrutura e servi\u00e7os<\/b><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Os investimentos se traduzem em amplia\u00e7\u00e3o da infraestrutura e do alcance dos servi\u00e7os p\u00fablicos, e ainda em gera\u00e7\u00e3o de empregos e renda.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Na \u00e1rea de Sa\u00fade, por exemplo, o Estado construiu 15 hospitais e 26 policl\u00ednicas regionais, e ainda 19 Centros de Aten\u00e7\u00e3o Psicossocial (Caps) e Unidades B\u00e1sicas de Sa\u00fade, criando uma infraestrutura que mostrou-se fundamental para a estrat\u00e9gia de enfrentamento aos efeitos da pandemia do novo coronav\u00edrus a partir de mar\u00e7o de 2020. Os novos equipamentos incluem o HGE 2, o Hospital da Mulher e o Instituto Couto Maia, em Salvador, o Hospital Regional Costa do Cacau, em Ilh\u00e9us, o Hospital da Chapada, em Seabra, a Maternidade do Hospital da Crian\u00e7a, em Feira de Santana, e o Hospital Metropolitano.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">A melhoria da infraestrutura da rede p\u00fablica estadual marca os investimentos em Educa\u00e7\u00e3o. A requalifica\u00e7\u00e3o da rede f\u00edsica escolar em curso nos \u00faltimos anos envolve a instala\u00e7\u00e3o de novos equipamentos, como laborat\u00f3rios, bibliotecas, quadras de esportes cobertas e campos society, e tem como destaque a entrega de novos Complexos Poliesportivos Educacionais destinados a fortalecer a aprendizagem no contexto da Educa\u00e7\u00e3o em Tempo Integral. Entre os complexos j\u00e1 entregues est\u00e3o os de Irec\u00ea, Concei\u00e7\u00e3o do Coit\u00e9, S\u00e3o Gon\u00e7alo dos Campos e Jequi\u00e9.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Na \u00e1rea de Seguran\u00e7a, o governo implementou o inovador Centro de Opera\u00e7\u00f5es e Intelig\u00eancia de Seguran\u00e7a P\u00fablica 2 de Julho, em Salvador, e ainda 22 Centros Integrados de Comunica\u00e7\u00e3o no interior, al\u00e9m de ter inaugurado 32 Distritos Integrados de Seguran\u00e7a, os Diseps. Foram realizadas ainda reformas totais ou parciais de 200 delegacias.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Os investimentos em urbanismo desde 2015 incluem ainda obras como a Via Barrad\u00e3o, a Linha Vermelha e a Linha Azul, na capital, e a ponte Ilh\u00e9us-Pontal, entre outras interven\u00e7\u00f5es estruturantes. Os investimentos em transporte incluem a expans\u00e3o do Metr\u00f4 de Salvador e Lauro de Freitas, a Via Metropolitana, na Regi\u00e3o Metropolitana de Salvador, e a constru\u00e7\u00e3o e recupera\u00e7\u00e3o de mais de oito mil quil\u00f4metros de estradas.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foram destinados R$ 7,7 bilh\u00f5es no per\u00edodo para Educa\u00e7\u00e3o, Sa\u00fade e Seguran\u00e7a P\u00fablica. No total investido, a Bahia manteve o segundo lugar entre os estados no per\u00edodo A \u00e1rea social liderou os investimentos do governo baiano entre 2015 e 2022, com um total de R$ 7,7 bilh\u00f5es destinados a Educa\u00e7\u00e3o, Sa\u00fade e Seguran\u00e7a P\u00fablica. Em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":113292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[74,72],"tags":[304,305,307,306],"_links":{"self":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/113291"}],"collection":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/comments?post=113291"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/113291\/revisions"}],"predecessor-version":[{"id":113296,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/posts\/113291\/revisions\/113296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media\/113292"}],"wp:attachment":[{"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/media?parent=113291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/categories?post=113291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdopaulonunes.com\/v5\/index.php\/wp-json\/wp\/v2\/tags?post=113291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}